{"id":2711,"date":"2025-04-08T12:47:26","date_gmt":"2025-04-08T10:47:26","guid":{"rendered":"https:\/\/www.rassismus-toetet-leipzig.org\/?p=2711"},"modified":"2025-04-08T12:58:38","modified_gmt":"2025-04-08T10:58:38","slug":"kritik-an-streichung-des-rechten-mordes-in-aue-durch-das-innenministerium-sachsen-und-aufruf-zur-gedenkdemonstration","status":"publish","type":"post","link":"https:\/\/www.rassismus-toetet-leipzig.org\/index.php\/kritik-an-streichung-des-rechten-mordes-in-aue-durch-das-innenministerium-sachsen-und-aufruf-zur-gedenkdemonstration\/","title":{"rendered":"Kritik an Streichung des rechten Mordes in Aue durch das Innenministerium Sachsen und Aufruf zur Gedenkdemonstration"},"content":{"rendered":"<p>Die Gruppe \u201eRassismus t\u00f6tet!&#8220; &#8211; Leipzig kritisiert die \u201eAusstufung&#8220; der brutalen T\u00f6tung von Christopher W. in Aue 2018 durch das Innenministerium Sachsen (1) und ruft zur breiten Beteiligung an der<br \/>\nGedenkdemonstration am 19. April 2025 in Aue von der Initiative \u201eSPEKTRUM 360\u00b0&#8220; auf.<\/p>\n<p>Derzeit gehen Opferberatungsstellen und Journalist*innen f\u00fcr den Zeitraum zwischen 1990 bis 2023 von mindestens 195 T\u00f6tungsdelikten mit rechten, rassistischen und antisemitischen Tatmotivation sowie von mindestens 65 Verdachtsf\u00e4llen in Deutschland aus. F\u00fcr den gleichen Zeitraum hat das Bundeskriminalamt lediglich 115 PMK-Rechts T\u00f6tungsdelikte anerkannt. (2)<\/p>\n<p>In Sachsen zeichnet sich ein \u00e4hnliches Bild, hier gehen Journalist*innen (3), Opferberatungsstellen und Initiativen wie \u201eRassismus t\u00f6tet!&#8220; &#8211; Leipzig von 17 rechtsmotivierten T\u00f6tungsdelikten seit 1990 aus, hinzu kommen 9 Verdachtsf\u00e4lle. Vom Innenministerium werden mit der Streichung des Mordes in Aue nur noch 9 T\u00f6tungsdelikte gez\u00e4hlt.<\/p>\n<p>Seit mehr als zehn Jahren erinnert die Gruppe \u201eRassismus t\u00f6tet!&#8220; &#8211; Leipzig in Sachsen an Todesopfer rechter Gewalt. Die Initiative begleitete zwei Mord-Prozesse gegen T\u00e4ter am Landgericht Leipzig (den<br \/>\nMord an Kamal K. 2010 in Leipzig und den Mord an Andr\u00e9 K. 2011 in Oschatz) und erarbeitete f\u00fcr die Region 2014 eine Ausstellung \u201eDie verschwiegenen Toten &#8211; Todesopfer rechter Gewalt in Leipzig seit 1990&#8243;, die aktuell \u00fcberarbeitet wird (4).<\/p>\n<p>Ein Sprecher der Gruppe &#8222;Rassismus t\u00f6tet!&#8220; &#8211; Leipzig, Hannes Heinze,<br \/>\nerkl\u00e4rt dazu:<\/p>\n<blockquote><p>In der Antwort des Innenministers zur Drucksache (8\/1829) wird der Eindruck erweckt, dass Landtagsanfragen urs\u00e4chlich f\u00fcr die \u201eAusstuftung&#8220; f\u00fcr den Mord in Aue sind. Wir erinnern uns hingegen daran, dass erst mehrmalige Landtagsanfragen nach unserer ver\u00f6ffentlichten Ausstellung notwendig waren, damit der Mord 2003 an dem Sch\u00fcler Thomas K. in Leipzig nach \u00fcber zehn Jahren anerkannt wurde (5). Seit Jahrzehnten wird die rechte Gewalt in Deutschland verharmlost und vertuscht, es hat sich nach bald 25 Jahren Auseinandersetzung mit diesem Thema, kaum etwas verbessert (6). Es scheint als w\u00fcrde jeder Strohhalm genutzt um rechtsmotivierte T\u00f6tungsdelikte nicht als solche benennen zu m\u00fcssen. Es ist unfassbar und macht w\u00fctend, immer wieder um jedes Todesopfer rechter Gewalt mit Beh\u00f6rden streiten zu m\u00fcssen.<\/p>\n<p>Es sind Angeh\u00f6rige, engagierte Nebenkl\u00e4ger*innen, Journalist*innen und Initiativen, wenn es sie denn in Gerichtsverhandlungen gibt, die immer wieder auf m\u00f6gliche Motive hinweisen m\u00fcssen und die Hintergr\u00fcnde der Taten \u00f6ffentlich machen, wie aktuell in Solingen (7). Es w\u00e4re ein wichtiges Zeichen, dass am 19. April bei der Gedenkdemonstration in Aue viele Menschen deutlich machen, dass der Mord an Christopher W. nicht vergessen wird und die Hintergr\u00fcnde der Tat nicht verschwiegen werden. Der Mord an Christopher W. muss wieder von Seiten der Beh\u00f6rden offiziell anerkannt werden. Dies fordern wir auch f\u00fcr die weiteren Todesopfer rechter Gewalt, die bis heute nicht anerkannt sind oder ebenfalls aus der Statistik nachtr\u00e4glich entfernt wurden.<\/p><\/blockquote>\n<p>Die Demonstration am 19. April 2025 startet um 14 Uhr am Bahnhof in Aue.<\/p>\n<p>(1) vgl.<a href=\"https:\/\/www.linksfraktionsachsen.de\/presse\/detail\/toetung-eines-mannes-2018-in-aue-gilt-nicht-mehr-als-rechtsmotivierte-straftat-juliane-nagel-weder-nachvollziehbar-noch-fachlich-haltbar\/\" target=\"_blank\" rel=\"noopener noreferrer\"> https:\/\/www.linksfraktionsachsen.de\/presse\/detail\/toetung-eines-mannes-2018-in-aue-gilt-nicht-mehr-als-rechtsmotivierte-straftat-juliane-nagel-weder-nachvollziehbar-noch-fachlich-haltbar\/<\/a><br \/>\n<a href=\"https:\/\/www.raa-sachsen.de\/support\/pressemeldungen\/toetung-von-christopher-w-innenministerium-in-sachsen-erkennt-kein-politisches-motiv-mehr-an-9431\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.raa-sachsen.de\/support\/pressemeldungen\/toetung-von-christopher-w-innenministerium-in-sachsen-erkennt-kein-politisches-motiv-mehr-an-9431<\/a><\/p>\n<p>(2)<a href=\"https:\/\/verband-brg.de\/stellungnahme-bleibende-anerkennungsluecken-fuer-todesopfer-rechter-gewalt\/\" target=\"_blank\" rel=\"noopener noreferrer\"> https:\/\/verband-brg.de\/stellungnahme-bleibende-anerkennungsluecken-fuer-todesopfer-rechter-gewalt\/<\/a><\/p>\n<p>(3) <a href=\"https:\/\/www.zeit.de\/gesellschaft\/zeitgeschehen\/2018-09\/todesopfer-rechte-gewalt-karte-portraet\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.zeit.de\/gesellschaft\/zeitgeschehen\/2018-09\/todesopfer-rechte-gewalt-karte-portraet<\/a><br \/>\n<a href=\"https:\/\/www.zeit.de\/gesellschaft\/zeitgeschehen\/2018-09\/rechtsxtremismus-todesopfer-gewalt-verdacht\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.zeit.de\/gesellschaft\/zeitgeschehen\/2018-09\/rechtsxtremismus-todesopfer-gewalt-verdacht<\/a><\/p>\n<p>(4) vgl. Seite 84<a href=\"https:\/\/chronikle.org\/leipziger-zustaende\/leipziger-zustaende-2025\" target=\"_blank\" rel=\"noopener noreferrer\"> https:\/\/chronikle.org\/leipziger-zustaende\/leipziger-zustaende-2025<\/a><\/p>\n<p>(5) <a href=\"https:\/\/www.l-iz.de\/leben\/faelle-unfaelle\/2015\/01\/Toetungsverbrechen-Innenministerium-erkennt-Opfer-rechter-Gewalt-an-62387\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.l-iz.de\/leben\/faelle-unfaelle\/2015\/01\/Toetungsverbrechen-Innenministerium-erkennt-Opfer-rechter-Gewalt-an-62387<\/a><br \/>\n<a href=\"https:\/\/www.inventati.org\/leipzig\/?p=3037\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.inventati.org\/leipzig\/?p=3037<\/a><br \/>\n<a href=\"https:\/\/www.l-iz.de\/politik\/sachsen\/2014\/08\/opfer-rechter-gewalt-was-nicht-ins-raster-passt-56671\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.l-iz.de\/politik\/sachsen\/2014\/08\/opfer-rechter-gewalt-was-nicht-ins-raster-passt-56671<\/a><\/p>\n<p>(6)<a href=\"https:\/\/www.ndr.de\/fernsehen\/sendungen\/panorama\/archiv\/2000\/Die-verschwiegenen-Toten-Behoerden-vertuschen-Ausmass-der-rechtsradikalen-Gewalt,erste7368.html\" target=\"_blank\" rel=\"noopener noreferrer\"> https:\/\/www.ndr.de\/fernsehen\/sendungen\/panorama\/archiv\/2000\/Die-verschwiegenen-Toten-Behoerden-vertuschen-Ausmass-der-rechtsradikalen-Gewalt,erste7368.html<\/a><\/p>\n<p>(7) <a href=\"https:\/\/www.nd-aktuell.de\/artikel\/1190381.behoerdenversagen-solingen-unterschlagung-von-beweismitteln.html\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.nd-aktuell.de\/artikel\/1190381.behoerdenversagen-solingen-unterschlagung-von-beweismitteln.html<\/a><br \/>\n<a href=\"https:\/\/taz.de\/Rassistische-Brandstiftung-in-Solingen\/!6080853\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/taz.de\/Rassistische-Brandstiftung-in-Solingen\/!6080853\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Gruppe \u201eRassismus t\u00f6tet!&#8220; &#8211; Leipzig kritisiert die \u201eAusstufung&#8220; der brutalen T\u00f6tung von Christopher W. in Aue 2018 durch das Innenministerium Sachsen (1) und ruft zur breiten Beteiligung an der Gedenkdemonstration am 19. April 2025 in Aue von der Initiative \u201eSPEKTRUM 360\u00b0&#8220; auf. Derzeit gehen Opferberatungsstellen und Journalist*innen f\u00fcr den Zeitraum zwischen 1990 bis 2023 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2712,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-2711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles"],"_links":{"self":[{"href":"https:\/\/www.rassismus-toetet-leipzig.org\/index.php\/wp-json\/wp\/v2\/posts\/2711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassismus-toetet-leipzig.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassismus-toetet-leipzig.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassismus-toetet-leipzig.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassismus-toetet-leipzig.org\/index.php\/wp-json\/wp\/v2\/comments?post=2711"}],"version-history":[{"count":2,"href":"https:\/\/www.rassismus-toetet-leipzig.org\/index.php\/wp-json\/wp\/v2\/posts\/2711\/revisions"}],"predecessor-version":[{"id":2823,"href":"https:\/\/www.rassismus-toetet-leipzig.org\/index.php\/wp-json\/wp\/v2\/posts\/2711\/revisions\/2823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassismus-toetet-leipzig.org\/index.php\/wp-json\/wp\/v2\/media\/2712"}],"wp:attachment":[{"href":"https:\/\/www.rassismus-toetet-leipzig.org\/index.php\/wp-json\/wp\/v2\/media?parent=2711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassismus-toetet-leipzig.org\/index.php\/wp-json\/wp\/v2\/categories?post=2711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassismus-toetet-leipzig.org\/index.php\/wp-json\/wp\/v2\/tags?post=2711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}